{"id":359,"date":"2022-12-28T10:22:43","date_gmt":"2022-12-28T10:22:43","guid":{"rendered":"https:\/\/hostex.io\/blog\/?p=359"},"modified":"2025-08-19T09:31:44","modified_gmt":"2025-08-19T09:31:44","slug":"the-airbnb-2022-winter-release","status":"publish","type":"post","link":"https:\/\/hostex.io\/blog\/de\/the-airbnb-2022-winter-release\/","title":{"rendered":"Was Sie \u00fcber die Winterversion von Airbnb 2022 wissen sollten"},"content":{"rendered":"<p>Jedes neue Airbnb-Update bringt eine Reihe spannender neuer Funktionen mit sich, wie AirCover und Split Stays im Airbnb <a rel=\"noreferrer noopener\" href=\"https:\/\/news.airbnb.com\/product-releases\/airbnb-2022-summer-release\/\" target=\"_blank\">Ver\u00f6ffentlichung im Sommer 2022<\/a>, was bei den meisten Gastgebern gut ankam.<\/p>\n\n\n\n<p>Allerdings k\u00f6nnen diese Aktualisierungen manchmal etwas umstritten sein und einen Vorteil f\u00fcr manche Hosts in einen Nachteil verwandeln.<\/p>\n\n\n\n<p>Mit <a rel=\"noreferrer noopener\" href=\"https:\/\/www.airbnb.com\/2022-winter\" target=\"_blank\">der Airbnb Winter Release 2022<\/a>, welche neuen Funktionen kommen und wie wirken sie sich auf Hosts aus? Lassen Sie uns einige Ansichten zu diesen Updates teilen.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>1. Noch mehr Aircover<\/strong><\/h2>\n\n\n\n<p><a rel=\"noreferrer noopener\" href=\"https:\/\/www.airbnb.com\/aircover-for-hosts\" target=\"_blank\">AirCover f\u00fcr Gastgeber<\/a> ist ein umfassender Schutz f\u00fcr Gastgeber. Er umfasst die Identit\u00e4ts\u00fcberpr\u00fcfung des Gastes, eine Reservierungspr\u00fcfung, Schadensschutz f\u00fcr Gastgeber, eine Haftpflichtversicherung f\u00fcr Gastgeber, eine Haftpflichtversicherung f\u00fcr Entdeckungen und eine 24-Stunden-Sicherheits-Hotline. Diese Schutzma\u00dfnahmen werden in der Winterversion 2022 von Airbnb noch weiter verbessert.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>$3M Schadensschutz<\/strong><\/h3>\n\n\n\n<p>Vrbo und Booking.com bieten Gastgebern eine Haftpflichtversicherung in H\u00f6he von $1.000.000 an, und wenn Airbnb noch mehr Aufmerksamkeit erlangen will, muss es die Messlatte noch h\u00f6her legen. AirCover bietet jetzt Schutz f\u00fcr geparkte Autos und Boote auf dem gelisteten Grundst\u00fcck sowie zus\u00e4tzlichen Schutz f\u00fcr Kunst und Wertgegenst\u00e4nde und erh\u00f6hten Schadensschutz. <strong>von $1 Millionen auf $3 Millionen<\/strong>.<\/p>\n\n\n\n<p>Dieser Schutz ist f\u00fcr neue Gastgeber sicherlich attraktiv. Wenn Sie als kurzfristiger Gastgeber beginnen, m\u00fcssen Sie in Ihrem Mietobjekt eine Reihe hochwertiger Verm\u00f6genswerte anbieten, die Buchungen anziehen, und wenn Sie Fremden erlauben, in Ihrem Haus zu \u00fcbernachten, k\u00f6nnen Sie beruhigt sein, wenn Sie das Gef\u00fchl haben, dass Ihre Verm\u00f6genswerte gesch\u00fctzt sind.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00dcberpr\u00fcfung der Gastidentit\u00e4t<\/strong><\/h3>\n\n\n\n<p>Das umfassende Verifizierungssystem pr\u00fcft Angaben wie Name, Adresse, Personalausweis und mehr, um die Identit\u00e4t von G\u00e4sten zu best\u00e4tigen, die \u00fcber Airbnb buchen.<\/p>\n\n\n\n<p>Derzeit deckt dies 901\u00a0Tausend aller Reservierungen ab, was f\u00fcr Gastgeber ein gro\u00dfer Vorteil ist, da sie sich dank eines strengeren \u00dcberpr\u00fcfungsprozesses darauf verlassen k\u00f6nnen, eine klarere Vorstellung davon zu haben, wer in ihrer Unterkunft \u00fcbernachten wird. Bis zum Fr\u00fchjahr 2023 werden 1001\u00a0Tausend aller weltweiten Buchungen verifiziert.<\/p>\n\n\n\n<p>Diese Funktion ist wichtig f\u00fcr Hosts, <strong>vor allem neue<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Funktionen zur Reservierungspr\u00fcfung<\/strong><\/h3>\n\n\n\n<p>Die firmeneigene Technologie von Airbnb analysiert Hunderte von Faktoren bei jeder Reservierung und <strong>blockiert bestimmte Buchungen, die ein hohes Risiko f\u00fcr st\u00f6rende Partys und Sachsch\u00e4den aufweisen<\/strong>.<\/p>\n\n\n\n<p>Nun erkl\u00e4rt Airbnb, dass diese Funktion exklusiv auf seinen Plattformen verf\u00fcgbar sei. Allerdings ist unklar, welche spezifischen Faktoren die Technologie ber\u00fccksichtigt und wie sie erfolgreich zwischen potenziellen Problemg\u00e4sten und gut erzogenen gro\u00dfen Gruppen unterscheiden kann. <\/p>\n\n\n\n<p>Allerdings blockiert diese Funktion alle Anfragen, die m\u00f6glicherweise gegen die Regeln versto\u00dfen k\u00f6nnten, und wird von der Mehrheit der Hosts mit Sicherheit positiv aufgenommen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Einfachere Schadensmeldung<\/strong><\/h3>\n\n\n\n<p>Diese Funktion soll es Gastgebern erleichtern, Airbnb und G\u00e4ste \u00fcber besch\u00e4digte oder verlorene\/gestohlene Gegenst\u00e4nde zu informieren. In einem einfachen und intuitiven Prozess k\u00f6nnen Gastgeber Airbnb \u00fcber einen kaputten oder fehlenden Gegenstand informieren und mitteilen, wie viel dieser wert war, wie alt er war und wann es passiert ist. Anschlie\u00dfend wird eine Zusammenfassung des Anspruchs sowohl an die Plattform als auch an den Gast weitergeleitet. Ziel ist es, Gastgebern zus\u00e4tzlichen Schutz zu bieten und ihnen im schlimmsten Fall eine Entsch\u00e4digung zuzusichern.<\/p>\n\n\n\n<p>F\u00fcr Gastgeber ist das Problem aber vielleicht nicht das vorherige Beschwerdeverfahren, sondern die Tatsache, dass Airbnb bei der Entscheidungsfindung eher die Rechte der G\u00e4ste sch\u00fctzt. Vielleicht w\u00fcrden mehr Gastgeber eine L\u00f6sung dieses \u00c4rgernisses begr\u00fc\u00dfen.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/news.airbnb.com\/wp-content\/uploads\/sites\/4\/2022\/05\/AirCover_PS_ENG_02.jpg?w=1024&amp;resize=3000%2C2000\" alt=\" \"\/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>2. Das brandneue Airbnb-Setup<\/strong><\/h2>\n\n\n\n<p>Die bevorstehende Rezession k\u00f6nnte mehr Menschen dazu veranlassen, mehr zu verdienen, indem sie ihre Inserate auf Airbnb vermieten. Im vergangenen Jahr haben fast 30 Millionen Menschen Airbnb besucht, um sich \u00fcber das Gastgeben zu informieren. Mit jedem neuen Produktupdate seit 2021 arbeitet Airbnb daran, die Einstiegsh\u00fcrde f\u00fcr neue Gastgeber zu senken.<\/p>\n\n\n\n<p>Vor diesem Hintergrund m\u00f6chte Airbnb das Hinzuf\u00fcgen Ihrer Immobilie als buchbare Unterkunft wesentlich einfacher machen. Die Winterversion 2022 von Airbnb Set Up soll dies m\u00f6glich machen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Pers\u00f6nliche Betreuung durch einen Superhost<\/strong><\/h3>\n\n\n\n<p>Dieser neue Ablauf f\u00fcr das Onboarding bietet neuen Gastgebern die M\u00f6glichkeit, mit einem bestehenden Superhost in der gleichen Gegend zusammengebracht zu werden, der sie w\u00e4hrend des gesamten Einrichtungsprozesses kostenlos anleiten und beraten kann. <\/p>\n\n\n\n<p>Neue Gastgeber k\u00f6nnen Videoanrufe t\u00e4tigen und ihren Bildschirm mit dem Superhost-Partner teilen, der ihnen beim Ausw\u00e4hlen der Fotos und Verfassen des Eintrags hilft und ihnen alle m\u00f6glichen Tipps gibt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Ein erfahrener Gast f\u00fcr die erste Buchung<\/strong><\/h3>\n\n\n\n<p>Neue Gastgeber k\u00f6nnen sich jetzt f\u00fcr ihre erste Buchung einen erfahrenen Gast aussuchen \u2013 jemanden mit mindestens drei Aufenthalten und einer guten Erfolgsbilanz bei Airbnb.<\/p>\n\n\n\n<p>Dadurch wird das Unterfangen f\u00fcr neue Gastgeber weniger entmutigend, da sie die Erfahrungen nutzen k\u00f6nnen, um sich zu verbessern und auf das Kundenfeedback zu reagieren.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Spezialisierte Unterst\u00fctzung von Airbnb<\/strong><\/h3>\n\n\n\n<p>Neue Gastgeber k\u00f6nnen die Supportmitarbeiter von Airbnb in 42 Sprachen erreichen, wenn sie Hilfe zu allen Themen ben\u00f6tigen, genau wie Superhosts.<\/p>\n\n\n\n<p>Es ist den meisten neuen Gastgebern gegen\u00fcber \u00e4u\u00dferst freundlich und es sieht so aus, als ob Airbnb bereit ist, mehr Zeit und Geld zu investieren, um neuen Gastgebern zu helfen, erfolgreich zu sein.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"746\" src=\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/image-7-1024x746.png\" alt=\"\" class=\"wp-image-1428\" srcset=\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/image-7-1024x746.png 1024w, https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/image-7-300x219.png 300w, https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/image-7-768x560.png 768w, https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/image-7.png 1212w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>3. Neue Airbnb-Kategorien<\/strong><\/h2>\n\n\n\n<p>Im Mai f\u00fchrte Airbnb eine neue Suchfunktion ein, die auf Airbnb-Kategorien basiert. Durch die Verwendung unterschiedlicher Kategorien kann der Eigent\u00fcmer sein Ferienhaus besser vermarkten und so die Bed\u00fcrfnisse und W\u00fcnsche potenzieller G\u00e4ste erf\u00fcllen.<\/p>\n\n\n\n<p>Jetzt gibt es sechs neue Kategorien in der Winterversion von Airbnb, die Gastgebern dabei helfen, ihren Markt und ihren Kundenstamm zu identifizieren. Au\u00dferdem k\u00f6nnen Gastgeber sehen, in welche Kategorie ihr Zuhause f\u00e4llt, und ihrem Eintrag kategoriespezifische Details hinzuf\u00fcgen.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/a0.muscache.com\/im\/pictures\/8ecbc24f-607a-4fa2-be23-61b7c1028b37.jpg?im_w=2560\" alt=\"A laptop and a phone show the Airbnb homepage with two rows of homes from a new Airbnb Winter Release category called Hanoks, which features traditional 14th century South Korean homes made of natural materials.\"\/><\/figure>\n\n\n\n<p>Airbnb verbessert auch die angezeigten Kategorien. Wenn Sie beispielsweise die App starten, wird Ihnen die Kategorie \u201eWeinberge\u201c angezeigt, wenn Sie k\u00fcrzlich nach H\u00e4usern in Napa gesucht haben. <\/p>\n\n\n\n<p>Dar\u00fcber hinaus werden Ihnen bei der Anzeige von Kategorien in Suchergebnissen mehr Details angezeigt. Beispielsweise wird bei H\u00e4usern mit atemberaubender Aussicht die Art der Aussicht aufgef\u00fchrt, und bei H\u00e4usern in der N\u00e4he von Nationalparks wird die Entfernung zum Parkeingang angezeigt.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>4. Grundregeln f\u00fcr G\u00e4ste<\/strong><\/h2>\n\n\n\n<p>Grundregeln sind Regeln, die von G\u00e4sten nicht gebrochen werden d\u00fcrfen. Sie sind eine willkommene Erg\u00e4nzung f\u00fcr Gastgeber, die bestimmte Richtlinien durchsetzen m\u00f6chten, da G\u00e4ste alle Grundregeln vor der Buchung lesen und ihnen zustimmen m\u00fcssen. Ein Gast wird entweder verwarnt, gesperrt oder von Airbnb entfernt, wenn er diese Regeln bricht.<\/p>\n\n\n\n<p>Tatsache ist, dass jeder Gastgeber schon immer Regeln f\u00fcr den Aufenthalt festgelegt hat. Dies ist jedoch nur eine Benachrichtigungsnachricht, die an die G\u00e4ste gesendet wird, und ob sie wirksam ist oder nicht, h\u00e4ngt von der St\u00e4rke der Durchsetzung ab. Ich hoffe, dass diese neue Funktion von Airbnb wirklich dazu beitragen kann, das Verhalten der G\u00e4ste einzuschr\u00e4nken.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>5. Upgrade der Bewertungen<\/strong><\/h2>\n\n\n\n<p>G\u00e4ste und Gastgeber k\u00f6nnen ihren Bewertungen jetzt Tags hinzuf\u00fcgen, um spezifischere Einzelheiten zum Aufenthalt anzugeben.<\/p>\n\n\n\n<p>Gastgeber k\u00f6nnen mit dieser Funktion beispielsweise aufzeichnen, ob der Gast gegen Grundregeln versto\u00dfen hat oder ob er seine Check-out-Zeit \u00fcberschritten hat. Auf diese Weise k\u00f6nnen andere Gastgeber, wenn sie eine Buchungsanfrage erhalten, diese Details sehen und eine bessere Entscheidung treffen.<\/p>\n\n\n\n<p>Airbnb hat zudem die Gr\u00fcnde erweitert, aus denen eine Bewertung angefochten werden kann. Gastgeber k\u00f6nnen nun leichter die Entfernung unfairer, als Vergeltung gedachter Bewertungen verlangen, unabh\u00e4ngig davon, wie lange diese her sind.<\/p>\n\n\n\n<p>Sie k\u00f6nnen Bewertungen an G\u00e4ste senden, G\u00e4stebewertungen einsehen und beantworten \u00fcber <a rel=\"noreferrer noopener\" href=\"https:\/\/hostex.io\/\" target=\"_blank\">Hostex<\/a>, Und <a rel=\"noreferrer noopener\" href=\"https:\/\/hostex.io\/blog\/airbnb-host-reviews-and-how-to-automate-them-with-review-examples\/\" target=\"_blank\">Alle diese Aktionen k\u00f6nnen automatisiert werden<\/a>. <strong>Melden Sie sich jetzt bei Hostex an, um Ihre verschiedenen Kan\u00e4le f\u00fcr Eintr\u00e4ge und Bewertungen zu automatisieren!<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/hostex.io\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"413\" src=\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/16_9\u5934\u56fe-1-1024x413.png\" alt=\"\" class=\"wp-image-1400\" srcset=\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/16_9\u5934\u56fe-1-1024x413.png 1024w, https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/16_9\u5934\u56fe-1-300x121.png 300w, https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/16_9\u5934\u56fe-1-768x310.png 768w, https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/16_9\u5934\u56fe-1-1536x620.png 1536w, https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/16_9\u5934\u56fe-1-2048x827.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>6. <strong>Schnelle Bezahlung<\/strong><\/strong><\/h2>\n\n\n\n<p>Das neue&nbsp;<strong>Schnelle Bezahlung<\/strong>&nbsp;Mit dieser Funktion k\u00f6nnen Hosts w\u00e4hlen, ob Auszahlungen innerhalb von 30 Minuten oder weniger auf ihre Debitkarte erfolgen sollen (nur in den USA verf\u00fcgbar).<\/p>\n\n\n\n<p>Dies wird den Druck auf kleine Gastgeber, die sehr empfindlich auf ihren Cashflow reagieren, erheblich verringern. Sie m\u00fcssen nicht 24 Stunden auf die Zahlung warten und k\u00f6nnen sich in Bezug auf ihre finanzielle Situation entspannter f\u00fchlen.<\/p>\n\n\n\n<p>Und Airbnb wird hierf\u00fcr eine Geb\u00fchr von 1,51 TP3T (mit einer H\u00f6chstgeb\u00fchr von 1 TP4T15 USD, ggf. einschlie\u00dflich Steuern) erheben, was f\u00fcr das Unternehmen ebenfalls eine M\u00f6glichkeit zur Gewinnsteigerung sein kann.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>7. Preise mit Reinigungsgeb\u00fchr<\/strong><\/h2>\n\n\n\n<p>Airbnb rechnet die Reinigungsgeb\u00fchr in den angezeigten Buchungspreis ein. So kann der Gast beim Durchsuchen des Inserats die Gesamtkosten bereits im Voraus sehen und muss nicht warten, bis die Buchung best\u00e4tigt ist. Dies erleichtert die Entscheidung und erspart unn\u00f6tige Zeitverschwendung.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p><strong>Haftungsausschluss: <a href=\"https:\/\/hostex.io\/\" target=\"_blank\" rel=\"noreferrer noopener\">Hostex<\/a> ist ein Softwarepartner von Airbnb. Dieser Beitrag, einschlie\u00dflich aller darin enthaltenen Anspr\u00fcche oder Aussagen, stammt ausschlie\u00dflich von Hostex und wird in keiner Weise von Airbnb unterst\u00fctzt, ist nicht direkt mit Airbnb verbunden, autorisiert oder gesponsert.<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Welche neuen Funktionen bringt das Winter-Release 2022 von Airbnb und welche Auswirkungen haben sie auf Gastgeber? Lassen Sie uns einige Ansichten zu diesen Updates teilen.<\/p>","protected":false},"author":1,"featured_media":1429,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[78],"tags":[88],"class_list":["post-359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-insights","tag-airbnb-release"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>What You Should Know About The Airbnb 2022 Winter Release? - Hostex<\/title>\n<meta name=\"description\" content=\"With the Airbnb 2022 Winter Release, what new features are coming, and how will they affect hosts? Let\u2019s share some views on these updates.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hostex.io\/blog\/de\/the-airbnb-2022-winter-release\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"What You Should Know About The Airbnb 2022 Winter Release? - Hostex\" \/>\n<meta property=\"og:description\" content=\"With the Airbnb 2022 Winter Release, what new features are coming, and how will they affect hosts? Let\u2019s share some views on these updates.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hostex.io\/blog\/de\/the-airbnb-2022-winter-release\/\" \/>\n<meta property=\"og:site_name\" content=\"Hostex\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Hostex.io\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Hostex.io\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-28T10:22:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-19T09:31:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/12\/airbnb-2022-winter-release-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Daniel Altman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/HostexApp\" \/>\n<meta name=\"twitter:site\" content=\"@HostexApp\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Altman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/\"},\"author\":{\"name\":\"Daniel Altman\",\"@id\":\"https:\/\/hostex.io\/blog\/#\/schema\/person\/21abfcce32dee155095d3e903b35d680\"},\"headline\":\"What You Should Know About The Airbnb 2022 Winter Release?\",\"datePublished\":\"2022-12-28T10:22:43+00:00\",\"dateModified\":\"2025-08-19T09:31:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/\"},\"wordCount\":1392,\"commentCount\":19,\"publisher\":{\"@id\":\"https:\/\/hostex.io\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/12\/airbnb-2022-winter-release-1.png\",\"keywords\":[\"airbnb release\"],\"articleSection\":[\"Insights\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/\",\"url\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/\",\"name\":\"What You Should Know About The Airbnb 2022 Winter Release? - Hostex\",\"isPartOf\":{\"@id\":\"https:\/\/hostex.io\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/12\/airbnb-2022-winter-release-1.png\",\"datePublished\":\"2022-12-28T10:22:43+00:00\",\"dateModified\":\"2025-08-19T09:31:44+00:00\",\"description\":\"With the Airbnb 2022 Winter Release, what new features are coming, and how will they affect hosts? Let\u2019s share some views on these updates.\",\"breadcrumb\":{\"@id\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#primaryimage\",\"url\":\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/12\/airbnb-2022-winter-release-1.png\",\"contentUrl\":\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/12\/airbnb-2022-winter-release-1.png\",\"width\":1920,\"height\":1080,\"caption\":\"Three iPhones displaying the Airbnb host onboarding flow: Superhost matching, first guest selection, and support access.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hostex.io\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"What You Should Know About The Airbnb 2022 Winter Release?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hostex.io\/blog\/#website\",\"url\":\"https:\/\/hostex.io\/blog\/\",\"name\":\"Hostex\",\"description\":\"Put your vacation rental on autopilot with AI\",\"publisher\":{\"@id\":\"https:\/\/hostex.io\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hostex.io\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hostex.io\/blog\/#organization\",\"name\":\"Hostex\",\"url\":\"https:\/\/hostex.io\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/hostex.io\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/11\/cropped-cropped-cropped-cropped-cropped-Hostex_logo-3-1.png\",\"contentUrl\":\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/11\/cropped-cropped-cropped-cropped-cropped-Hostex_logo-3-1.png\",\"width\":1979,\"height\":506,\"caption\":\"Hostex\"},\"image\":{\"@id\":\"https:\/\/hostex.io\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Hostex.io\/\",\"https:\/\/x.com\/HostexApp\",\"https:\/\/www.instagram.com\/hostex.io\/\",\"https:\/\/www.youtube.com\/channel\/UCGeqVXi3XuEkCwFyoH6WxPA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/hostex.io\/blog\/#\/schema\/person\/21abfcce32dee155095d3e903b35d680\",\"name\":\"Daniel Altman\",\"sameAs\":[\"https:\/\/hostex.io\/\",\"https:\/\/www.facebook.com\/Hostex.io\",\"https:\/\/www.instagram.com\/hostex.io\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/HostexApp\",\"https:\/\/www.youtube.com\/channel\/UCGeqVXi3XuEkCwFyoH6WxPA\"],\"url\":\"https:\/\/hostex.io\/blog\/de\/author\/root\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"What You Should Know About The Airbnb 2022 Winter Release? - Hostex","description":"Welche neuen Funktionen bringt das Winter-Release 2022 von Airbnb und welche Auswirkungen haben sie auf Gastgeber? Lassen Sie uns einige Ansichten zu diesen Updates teilen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hostex.io\/blog\/de\/the-airbnb-2022-winter-release\/","og_locale":"de_DE","og_type":"article","og_title":"What You Should Know About The Airbnb 2022 Winter Release? - Hostex","og_description":"With the Airbnb 2022 Winter Release, what new features are coming, and how will they affect hosts? Let\u2019s share some views on these updates.","og_url":"https:\/\/hostex.io\/blog\/de\/the-airbnb-2022-winter-release\/","og_site_name":"Hostex","article_publisher":"https:\/\/www.facebook.com\/Hostex.io\/","article_author":"https:\/\/www.facebook.com\/Hostex.io","article_published_time":"2022-12-28T10:22:43+00:00","article_modified_time":"2025-08-19T09:31:44+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/12\/airbnb-2022-winter-release-1.png","type":"image\/png"}],"author":"Daniel Altman","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/HostexApp","twitter_site":"@HostexApp","twitter_misc":{"Verfasst von":"Daniel Altman","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#article","isPartOf":{"@id":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/"},"author":{"name":"Daniel Altman","@id":"https:\/\/hostex.io\/blog\/#\/schema\/person\/21abfcce32dee155095d3e903b35d680"},"headline":"What You Should Know About The Airbnb 2022 Winter Release?","datePublished":"2022-12-28T10:22:43+00:00","dateModified":"2025-08-19T09:31:44+00:00","mainEntityOfPage":{"@id":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/"},"wordCount":1392,"commentCount":19,"publisher":{"@id":"https:\/\/hostex.io\/blog\/#organization"},"image":{"@id":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#primaryimage"},"thumbnailUrl":"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/12\/airbnb-2022-winter-release-1.png","keywords":["airbnb release"],"articleSection":["Insights"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/","url":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/","name":"What You Should Know About The Airbnb 2022 Winter Release? - Hostex","isPartOf":{"@id":"https:\/\/hostex.io\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#primaryimage"},"image":{"@id":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#primaryimage"},"thumbnailUrl":"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/12\/airbnb-2022-winter-release-1.png","datePublished":"2022-12-28T10:22:43+00:00","dateModified":"2025-08-19T09:31:44+00:00","description":"Welche neuen Funktionen bringt das Winter-Release 2022 von Airbnb und welche Auswirkungen haben sie auf Gastgeber? Lassen Sie uns einige Ansichten zu diesen Updates teilen.","breadcrumb":{"@id":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#primaryimage","url":"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/12\/airbnb-2022-winter-release-1.png","contentUrl":"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/12\/airbnb-2022-winter-release-1.png","width":1920,"height":1080,"caption":"Three iPhones displaying the Airbnb host onboarding flow: Superhost matching, first guest selection, and support access."},{"@type":"BreadcrumbList","@id":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hostex.io\/blog\/"},{"@type":"ListItem","position":2,"name":"What You Should Know About The Airbnb 2022 Winter Release?"}]},{"@type":"WebSite","@id":"https:\/\/hostex.io\/blog\/#website","url":"https:\/\/hostex.io\/blog\/","name":"Hostex","description":"Schalten Sie Ihre Ferienwohnung mit KI auf Autopilot","publisher":{"@id":"https:\/\/hostex.io\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hostex.io\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/hostex.io\/blog\/#organization","name":"Hostex","url":"https:\/\/hostex.io\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hostex.io\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/11\/cropped-cropped-cropped-cropped-cropped-Hostex_logo-3-1.png","contentUrl":"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/11\/cropped-cropped-cropped-cropped-cropped-Hostex_logo-3-1.png","width":1979,"height":506,"caption":"Hostex"},"image":{"@id":"https:\/\/hostex.io\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Hostex.io\/","https:\/\/x.com\/HostexApp","https:\/\/www.instagram.com\/hostex.io\/","https:\/\/www.youtube.com\/channel\/UCGeqVXi3XuEkCwFyoH6WxPA"]},{"@type":"Person","@id":"https:\/\/hostex.io\/blog\/#\/schema\/person\/21abfcce32dee155095d3e903b35d680","name":"Daniel Altman","sameAs":["https:\/\/hostex.io\/","https:\/\/www.facebook.com\/Hostex.io","https:\/\/www.instagram.com\/hostex.io\/","https:\/\/x.com\/https:\/\/twitter.com\/HostexApp","https:\/\/www.youtube.com\/channel\/UCGeqVXi3XuEkCwFyoH6WxPA"],"url":"https:\/\/hostex.io\/blog\/de\/author\/root\/"}]}},"_links":{"self":[{"href":"https:\/\/hostex.io\/blog\/de\/wp-json\/wp\/v2\/posts\/359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hostex.io\/blog\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hostex.io\/blog\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hostex.io\/blog\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hostex.io\/blog\/de\/wp-json\/wp\/v2\/comments?post=359"}],"version-history":[{"count":17,"href":"https:\/\/hostex.io\/blog\/de\/wp-json\/wp\/v2\/posts\/359\/revisions"}],"predecessor-version":[{"id":1430,"href":"https:\/\/hostex.io\/blog\/de\/wp-json\/wp\/v2\/posts\/359\/revisions\/1430"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hostex.io\/blog\/de\/wp-json\/wp\/v2\/media\/1429"}],"wp:attachment":[{"href":"https:\/\/hostex.io\/blog\/de\/wp-json\/wp\/v2\/media?parent=359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hostex.io\/blog\/de\/wp-json\/wp\/v2\/categories?post=359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hostex.io\/blog\/de\/wp-json\/wp\/v2\/tags?post=359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}