{"id":359,"date":"2022-12-28T10:22:43","date_gmt":"2022-12-28T10:22:43","guid":{"rendered":"https:\/\/hostex.io\/blog\/?p=359"},"modified":"2025-08-19T09:31:44","modified_gmt":"2025-08-19T09:31:44","slug":"the-airbnb-2022-winter-release","status":"publish","type":"post","link":"https:\/\/hostex.io\/blog\/es\/the-airbnb-2022-winter-release\/","title":{"rendered":"\u00bfQu\u00e9 debes saber sobre el lanzamiento de invierno de Airbnb 2022?"},"content":{"rendered":"<p>Cada nueva actualizaci\u00f3n de Airbnb viene con una serie de nuevas y emocionantes funciones, como AirCover y Split Stays en Airbnb. <a rel=\"noreferrer noopener\" href=\"https:\/\/news.airbnb.com\/product-releases\/airbnb-2022-summer-release\/\" target=\"_blank\">Lanzamiento de verano de 2022<\/a>, que ha sido bien recibido por la mayor\u00eda de los anfitriones.<\/p>\n\n\n\n<p>Sin embargo, a veces estas actualizaciones pueden ser algo controvertidas y podr\u00edan convertir lo que era una ventaja para algunos hosts en una desventaja.<\/p>\n\n\n\n<p>Con <a rel=\"noreferrer noopener\" href=\"https:\/\/www.airbnb.com\/2022-winter\" target=\"_blank\">Lanzamiento de invierno de Airbnb 2022<\/a>\u00bfQu\u00e9 nuevas funciones se vienen y c\u00f3mo afectar\u00e1n a los hosts? Compartamos algunas opiniones sobre estas actualizaciones.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>1. A\u00fan m\u00e1s cobertura a\u00e9rea<\/strong><\/h2>\n\n\n\n<p><a rel=\"noreferrer noopener\" href=\"https:\/\/www.airbnb.com\/aircover-for-hosts\" target=\"_blank\">AirCover para anfitriones<\/a> es una protecci\u00f3n integral para los anfitriones. Incluye verificaci\u00f3n de identidad de los hu\u00e9spedes, evaluaci\u00f3n de reservas, protecci\u00f3n contra da\u00f1os para anfitriones, seguro de responsabilidad civil para anfitriones, seguro de responsabilidad civil para experiencias y una l\u00ednea de seguridad disponible las 24 horas. Estas protecciones se mejoran a\u00fan m\u00e1s en la versi\u00f3n de invierno de Airbnb de 2022.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Protecci\u00f3n contra da\u00f1os $3M<\/strong><\/h3>\n\n\n\n<p>Vrbo y Booking.com ofrecen un seguro de responsabilidad civil de $1,000,000 a los anfitriones, y si Airbnb quiere obtener a\u00fan m\u00e1s atenci\u00f3n, tendr\u00e1 que subir el list\u00f3n a\u00fan m\u00e1s, por lo que AirCover ahora ofrece protecci\u00f3n para autom\u00f3viles y botes estacionados en la propiedad listada, as\u00ed como protecci\u00f3n adicional para arte y objetos de valor y una mayor protecci\u00f3n contra da\u00f1os. <strong>De $1 mill\u00f3n a $3 millones<\/strong>.<\/p>\n\n\n\n<p>Esta protecci\u00f3n es ciertamente atractiva para los nuevos anfitriones. Cuando comienzas como anfitri\u00f3n de corto plazo, est\u00e1s obligado a ofrecer una serie de activos de alto valor en tu propiedad de alquiler que atraer\u00e1n reservas, y cuando permites que extra\u00f1os se alojen en tu casa, tendr\u00e1s mucha tranquilidad si sientes que tus activos est\u00e1n bajo protecci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Verificaci\u00f3n de identidad del hu\u00e9sped<\/strong><\/h3>\n\n\n\n<p>El sistema de verificaci\u00f3n integral verifica detalles como nombre, direcci\u00f3n, identificaci\u00f3n gubernamental y m\u00e1s para confirmar la identidad de los hu\u00e9spedes que reservan en Airbnb.<\/p>\n\n\n\n<p>Actualmente, esto cubre el 90% de todas las reservas, lo que es una gran ventaja para los anfitriones, ya que pueden confiar en tener una idea m\u00e1s clara de qui\u00e9n se hospedar\u00e1 en su propiedad, gracias a un proceso de verificaci\u00f3n m\u00e1s estricto. Para la primavera de 2023, se verificar\u00e1n el 100% de todas las reservas globales.<\/p>\n\n\n\n<p>Esta caracter\u00edstica es importante para los anfitriones, <strong>especialmente los nuevos<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Funciones de filtrado de reservas<\/strong><\/h3>\n\n\n\n<p>La tecnolog\u00eda patentada de Airbnb analiza cientos de factores en cada reserva y <strong>bloquea ciertas reservas que muestran un alto riesgo de fiestas disruptivas y da\u00f1os a la propiedad<\/strong>.<\/p>\n\n\n\n<p>Ahora bien, Airbnb dice que esto es exclusivo de sus plataformas, pero no est\u00e1 claro qu\u00e9 factores espec\u00edficos tiene en cuenta la tecnolog\u00eda y c\u00f3mo puede diferenciar con \u00e9xito entre hu\u00e9spedes potencialmente problem\u00e1ticos y grupos grandes que se comportan bien. <\/p>\n\n\n\n<p>Sin embargo, esta funci\u00f3n bloquear\u00e1 cualquier solicitud que parezca una potencial infracci\u00f3n de las reglas y seguramente ser\u00e1 bien recibida por la mayor\u00eda de los anfitriones.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Es m\u00e1s f\u00e1cil presentar una reclamaci\u00f3n<\/strong><\/h3>\n\n\n\n<p>Esta funci\u00f3n est\u00e1 dise\u00f1ada para facilitar a los anfitriones la notificaci\u00f3n a Airbnb y a los hu\u00e9spedes sobre art\u00edculos da\u00f1ados o perdidos\/robados. Siguiendo un proceso simple e intuitivo, los anfitriones pueden informar a Airbnb sobre un art\u00edculo roto o faltante, su valor, su antig\u00fcedad y cu\u00e1ndo sucedi\u00f3. Luego, se env\u00eda un resumen de la reclamaci\u00f3n tanto a la plataforma como al hu\u00e9sped. El objetivo es brindar mayor protecci\u00f3n a los anfitriones y al mismo tiempo garantizarles un reembolso en el peor de los casos.<\/p>\n\n\n\n<p>Pero para los anfitriones, lo preocupante puede no ser el proceso de reclamaciones anterior, sino el hecho de que Airbnb tiende a favorecer la protecci\u00f3n de los derechos de los hu\u00e9spedes a la hora de tomar decisiones. Tal vez m\u00e1s anfitriones agradecer\u00edan que se abordara esta molestia.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/news.airbnb.com\/wp-content\/uploads\/sites\/4\/2022\/05\/AirCover_PS_ENG_02.jpg?w=1024&amp;resize=3000%2C2000\" alt=\" \"\/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>2. La nueva configuraci\u00f3n de Airbnb<\/strong><\/h2>\n\n\n\n<p>La recesi\u00f3n que se avecina puede impulsar a m\u00e1s personas a intentar ganar m\u00e1s dinero alquilando sus propiedades en Airbnb. Durante el \u00faltimo a\u00f1o, casi 30 millones de personas visitaron Airbnb para obtener informaci\u00f3n sobre c\u00f3mo ser anfitri\u00f3n. Por eso, con cada nueva actualizaci\u00f3n de producto desde 2021, Airbnb est\u00e1 trabajando para reducir las barreras para que los nuevos anfitriones comiencen a trabajar en esta plataforma.<\/p>\n\n\n\n<p>Con esto en mente, Airbnb quiere que sea mucho m\u00e1s f\u00e1cil agregar su propiedad como alojamiento reservable, y la versi\u00f3n de invierno de Airbnb Set Up 2022 est\u00e1 dise\u00f1ada para que esto sea una realidad.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Orientaci\u00f3n personalizada de un SuperAnfitri\u00f3n<\/strong><\/h3>\n\n\n\n<p>Este nuevo flujo de incorporaci\u00f3n ofrece a los anfitriones novatos la oportunidad de ser emparejados con un SuperAnfitri\u00f3n existente en la misma \u00e1rea que puede guiarlos y asesorarlos durante todo el proceso de configuraci\u00f3n sin cargo. <\/p>\n\n\n\n<p>Los nuevos anfitriones pueden realizar videollamadas y compartir su pantalla con su SuperAnfitri\u00f3n asociado, quien los ayudar\u00e1 a seleccionar fotos, escribir su anuncio y compartir cualquier sugerencia que pueda tener.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Un hu\u00e9sped experimentado para la primera reserva.<\/strong><\/h3>\n\n\n\n<p>Ahora los nuevos anfitriones pueden elegir hospedar a un hu\u00e9sped experimentado para su primera reserva: alguien con al menos tres estad\u00edas y un buen historial en Airbnb.<\/p>\n\n\n\n<p>Esto hace que sea una propuesta menos desalentadora para los nuevos anfitriones, quienes pueden usar la experiencia para mejorar y actuar en funci\u00f3n de los comentarios de los clientes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Soporte especializado de Airbnb<\/strong><\/h3>\n\n\n\n<p>Los nuevos anfitriones pueden comunicarse con los agentes de soporte de Airbnb para obtener ayuda con cualquier cosa en 42 idiomas, tal como ocurre con los SuperAnfitriones.<\/p>\n\n\n\n<p>Es extremadamente amigable con la mayor\u00eda de los nuevos anfitriones y parece que Airbnb est\u00e1 dispuesto a gastar m\u00e1s tiempo y dinero para ayudar a los nuevos anfitriones a encaminarse hacia el \u00e9xito.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"746\" src=\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/image-7-1024x746.png\" alt=\"\" class=\"wp-image-1428\" srcset=\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/image-7-1024x746.png 1024w, https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/image-7-300x219.png 300w, https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/image-7-768x560.png 768w, https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/image-7.png 1212w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>3. Nuevas categor\u00edas de Airbnb<\/strong><\/h2>\n\n\n\n<p>En mayo, Airbnb present\u00f3 una nueva forma de b\u00fasqueda dise\u00f1ada en torno a las categor\u00edas de Airbnb. Tener categor\u00edas distintivas permitir\u00e1 al propietario promocionar su casa de vacaciones para satisfacer mejor las necesidades y los deseos de los hu\u00e9spedes potenciales.<\/p>\n\n\n\n<p>Ahora, hay seis nuevas categor\u00edas en la versi\u00f3n de invierno de Airbnb para ayudar a los anfitriones a identificar su mercado y su base de clientes, y los anfitriones podr\u00e1n ver en qu\u00e9 categor\u00eda se encuentra su casa y agregar detalles espec\u00edficos de la categor\u00eda a su anuncio.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/a0.muscache.com\/im\/pictures\/8ecbc24f-607a-4fa2-be23-61b7c1028b37.jpg?im_w=2560\" alt=\"A laptop and a phone show the Airbnb homepage with two rows of homes from a new Airbnb Winter Release category called Hanoks, which features traditional 14th century South Korean homes made of natural materials.\"\/><\/figure>\n\n\n\n<p>Airbnb tambi\u00e9n est\u00e1 mejorando las categor\u00edas que se muestran. Por ejemplo, cuando inicies la aplicaci\u00f3n, ver\u00e1s la categor\u00eda Vi\u00f1edos si buscaste recientemente casas en Napa. <\/p>\n\n\n\n<p>Adem\u00e1s, ver\u00e1s m\u00e1s detalles al visualizar las categor\u00edas en los resultados de b\u00fasqueda. Por ejemplo, las casas con vistas incre\u00edbles mostrar\u00e1n el tipo de vista y las casas cerca de parques nacionales mostrar\u00e1n la distancia hasta la entrada del parque.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>4. Normas b\u00e1sicas para los hu\u00e9spedes<\/strong><\/h2>\n\n\n\n<p>Las reglas b\u00e1sicas son aquellas que los hu\u00e9spedes no pueden romper. Es una buena opci\u00f3n para los anfitriones que desean aplicar pol\u00edticas espec\u00edficas, ya que los hu\u00e9spedes deben leer y aceptar todas las reglas b\u00e1sicas antes de realizar la reserva. Si un hu\u00e9sped no cumple con estas reglas, recibir\u00e1 una advertencia, ser\u00e1 suspendido o expulsado de Airbnb.<\/p>\n\n\n\n<p>El hecho es que cada anfitri\u00f3n siempre ha establecido reglas para la estancia, sin embargo, esto es solo un mensaje de texto que se env\u00eda a los hu\u00e9spedes y su efectividad o no depende de la fuerza con la que se haga cumplir. Espero que esta nueva funci\u00f3n de Airbnb pueda realmente desempe\u00f1ar un papel en la restricci\u00f3n del comportamiento de los hu\u00e9spedes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>5. Actualizaci\u00f3n de las Rese\u00f1as<\/strong><\/h2>\n\n\n\n<p>Los hu\u00e9spedes y anfitriones ahora pueden agregar etiquetas a sus rese\u00f1as para brindar detalles m\u00e1s espec\u00edficos sobre la estad\u00eda.<\/p>\n\n\n\n<p>Para los anfitriones, esta funci\u00f3n les permitir\u00e1 registrar, entre otras cosas, si el hu\u00e9sped incumpli\u00f3 alguna regla b\u00e1sica o si super\u00f3 la hora de salida. De esta manera, cuando otros anfitriones reciban una solicitud de reserva, ver\u00e1n estos detalles y tomar\u00e1n una mejor decisi\u00f3n.<\/p>\n\n\n\n<p>Airbnb tambi\u00e9n ampli\u00f3 las razones por las que se puede disputar una rese\u00f1a y ahora es m\u00e1s f\u00e1cil para los anfitriones solicitar la eliminaci\u00f3n de rese\u00f1as injustas y represalias sin importar cu\u00e1nto tiempo haya pasado desde que se dejaron.<\/p>\n\n\n\n<p>Puede enviar rese\u00f1as a los hu\u00e9spedes, verlas y responderlas a trav\u00e9s de <a rel=\"noreferrer noopener\" href=\"https:\/\/hostex.io\/\" target=\"_blank\">Hostex<\/a>, y <a rel=\"noreferrer noopener\" href=\"https:\/\/hostex.io\/blog\/airbnb-host-reviews-and-how-to-automate-them-with-review-examples\/\" target=\"_blank\">Todas estas acciones se pueden automatizar.<\/a>. <strong>\u00a1Reg\u00edstrese ahora en Hostex para automatizar sus m\u00faltiples canales de listados y rese\u00f1as!<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/hostex.io\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"413\" src=\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/16_9\u5934\u56fe-1-1024x413.png\" alt=\"\" class=\"wp-image-1400\" srcset=\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/16_9\u5934\u56fe-1-1024x413.png 1024w, https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/16_9\u5934\u56fe-1-300x121.png 300w, https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/16_9\u5934\u56fe-1-768x310.png 768w, https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/16_9\u5934\u56fe-1-1536x620.png 1536w, https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/16_9\u5934\u56fe-1-2048x827.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>6. <strong>Pago r\u00e1pido<\/strong><\/strong><\/h2>\n\n\n\n<p>El nuevo&nbsp;<strong>Pago r\u00e1pido<\/strong>&nbsp;Esta funci\u00f3n permite a los anfitriones elegir recibir los pagos en su tarjeta de d\u00e9bito en 30 minutos o menos (disponible solo en EE. UU.).<\/p>\n\n\n\n<p>Esto ayudar\u00e1 mucho a aliviar la presi\u00f3n sobre los peque\u00f1os anfitriones, que son muy sensibles al flujo de efectivo. No es necesario esperar 24 horas para recibir el pago y har\u00e1 que los anfitriones se sientan m\u00e1s tranquilos con su situaci\u00f3n financiera.<\/p>\n\n\n\n<p>Y Airbnb cobrar\u00e1 una tarifa de 1,51 TP3T (con una tarifa m\u00e1xima de 1 TP4T15 USD, incluidos los impuestos si corresponde) por esto, lo que tambi\u00e9n puede ser una forma de aumentar sus ganancias.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>7. Precios con tarifa de limpieza<\/strong><\/h2>\n\n\n\n<p>Airbnb incluir\u00e1 la tarifa de limpieza en el precio de reserva mostrado, lo que permitir\u00e1 al hu\u00e9sped ver el costo total que pagar\u00e1 de antemano mientras navega por el anuncio, en lugar de esperar hasta que se confirme la reserva, lo que facilitar\u00e1 la toma de una decisi\u00f3n y ahorrar\u00e1 p\u00e9rdidas de tiempo innecesarias.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p><strong>Descargo de responsabilidad: <a href=\"https:\/\/hostex.io\/\" target=\"_blank\" rel=\"noreferrer noopener\">Hostex<\/a> es un socio de software de Airbnb. Esta publicaci\u00f3n, incluidas todas las afirmaciones o declaraciones contenidas en ella, es \u00fanicamente de Hostex y no est\u00e1 respaldada por Airbnb, no est\u00e1 directamente afiliada a Airbnb, no est\u00e1 autorizada ni patrocinada por esta empresa de ninguna manera.<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Con la versi\u00f3n de invierno de Airbnb 2022, \u00bfqu\u00e9 nuevas funciones se incorporan y c\u00f3mo afectar\u00e1n a los anfitriones? Compartamos algunas opiniones sobre estas actualizaciones.<\/p>","protected":false},"author":1,"featured_media":1429,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[78],"tags":[88],"class_list":["post-359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-insights","tag-airbnb-release"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>What You Should Know About The Airbnb 2022 Winter Release? - Hostex<\/title>\n<meta name=\"description\" content=\"With the Airbnb 2022 Winter Release, what new features are coming, and how will they affect hosts? Let\u2019s share some views on these updates.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hostex.io\/blog\/es\/the-airbnb-2022-winter-release\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"What You Should Know About The Airbnb 2022 Winter Release? - Hostex\" \/>\n<meta property=\"og:description\" content=\"With the Airbnb 2022 Winter Release, what new features are coming, and how will they affect hosts? Let\u2019s share some views on these updates.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hostex.io\/blog\/es\/the-airbnb-2022-winter-release\/\" \/>\n<meta property=\"og:site_name\" content=\"Hostex\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Hostex.io\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Hostex.io\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-28T10:22:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-19T09:31:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/12\/airbnb-2022-winter-release-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Daniel Altman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/HostexApp\" \/>\n<meta name=\"twitter:site\" content=\"@HostexApp\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Altman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/\"},\"author\":{\"name\":\"Daniel Altman\",\"@id\":\"https:\/\/hostex.io\/blog\/#\/schema\/person\/21abfcce32dee155095d3e903b35d680\"},\"headline\":\"What You Should Know About The Airbnb 2022 Winter Release?\",\"datePublished\":\"2022-12-28T10:22:43+00:00\",\"dateModified\":\"2025-08-19T09:31:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/\"},\"wordCount\":1392,\"commentCount\":19,\"publisher\":{\"@id\":\"https:\/\/hostex.io\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/12\/airbnb-2022-winter-release-1.png\",\"keywords\":[\"airbnb release\"],\"articleSection\":[\"Insights\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/\",\"url\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/\",\"name\":\"What You Should Know About The Airbnb 2022 Winter Release? - Hostex\",\"isPartOf\":{\"@id\":\"https:\/\/hostex.io\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/12\/airbnb-2022-winter-release-1.png\",\"datePublished\":\"2022-12-28T10:22:43+00:00\",\"dateModified\":\"2025-08-19T09:31:44+00:00\",\"description\":\"With the Airbnb 2022 Winter Release, what new features are coming, and how will they affect hosts? Let\u2019s share some views on these updates.\",\"breadcrumb\":{\"@id\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#primaryimage\",\"url\":\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/12\/airbnb-2022-winter-release-1.png\",\"contentUrl\":\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/12\/airbnb-2022-winter-release-1.png\",\"width\":1920,\"height\":1080,\"caption\":\"Three iPhones displaying the Airbnb host onboarding flow: Superhost matching, first guest selection, and support access.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hostex.io\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"What You Should Know About The Airbnb 2022 Winter Release?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hostex.io\/blog\/#website\",\"url\":\"https:\/\/hostex.io\/blog\/\",\"name\":\"Hostex\",\"description\":\"Put your vacation rental on autopilot with AI\",\"publisher\":{\"@id\":\"https:\/\/hostex.io\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hostex.io\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hostex.io\/blog\/#organization\",\"name\":\"Hostex\",\"url\":\"https:\/\/hostex.io\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/hostex.io\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/11\/cropped-cropped-cropped-cropped-cropped-Hostex_logo-3-1.png\",\"contentUrl\":\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/11\/cropped-cropped-cropped-cropped-cropped-Hostex_logo-3-1.png\",\"width\":1979,\"height\":506,\"caption\":\"Hostex\"},\"image\":{\"@id\":\"https:\/\/hostex.io\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Hostex.io\/\",\"https:\/\/x.com\/HostexApp\",\"https:\/\/www.instagram.com\/hostex.io\/\",\"https:\/\/www.youtube.com\/channel\/UCGeqVXi3XuEkCwFyoH6WxPA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/hostex.io\/blog\/#\/schema\/person\/21abfcce32dee155095d3e903b35d680\",\"name\":\"Daniel Altman\",\"sameAs\":[\"https:\/\/hostex.io\/\",\"https:\/\/www.facebook.com\/Hostex.io\",\"https:\/\/www.instagram.com\/hostex.io\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/HostexApp\",\"https:\/\/www.youtube.com\/channel\/UCGeqVXi3XuEkCwFyoH6WxPA\"],\"url\":\"https:\/\/hostex.io\/blog\/es\/author\/root\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"What You Should Know About The Airbnb 2022 Winter Release? - Hostex","description":"Con la versi\u00f3n de invierno de Airbnb 2022, \u00bfqu\u00e9 nuevas funciones se incorporan y c\u00f3mo afectar\u00e1n a los anfitriones? Compartamos algunas opiniones sobre estas actualizaciones.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hostex.io\/blog\/es\/the-airbnb-2022-winter-release\/","og_locale":"es_ES","og_type":"article","og_title":"What You Should Know About The Airbnb 2022 Winter Release? - Hostex","og_description":"With the Airbnb 2022 Winter Release, what new features are coming, and how will they affect hosts? Let\u2019s share some views on these updates.","og_url":"https:\/\/hostex.io\/blog\/es\/the-airbnb-2022-winter-release\/","og_site_name":"Hostex","article_publisher":"https:\/\/www.facebook.com\/Hostex.io\/","article_author":"https:\/\/www.facebook.com\/Hostex.io","article_published_time":"2022-12-28T10:22:43+00:00","article_modified_time":"2025-08-19T09:31:44+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/12\/airbnb-2022-winter-release-1.png","type":"image\/png"}],"author":"Daniel Altman","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/HostexApp","twitter_site":"@HostexApp","twitter_misc":{"Escrito por":"Daniel Altman","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#article","isPartOf":{"@id":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/"},"author":{"name":"Daniel Altman","@id":"https:\/\/hostex.io\/blog\/#\/schema\/person\/21abfcce32dee155095d3e903b35d680"},"headline":"What You Should Know About The Airbnb 2022 Winter Release?","datePublished":"2022-12-28T10:22:43+00:00","dateModified":"2025-08-19T09:31:44+00:00","mainEntityOfPage":{"@id":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/"},"wordCount":1392,"commentCount":19,"publisher":{"@id":"https:\/\/hostex.io\/blog\/#organization"},"image":{"@id":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#primaryimage"},"thumbnailUrl":"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/12\/airbnb-2022-winter-release-1.png","keywords":["airbnb release"],"articleSection":["Insights"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/","url":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/","name":"What You Should Know About The Airbnb 2022 Winter Release? - Hostex","isPartOf":{"@id":"https:\/\/hostex.io\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#primaryimage"},"image":{"@id":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#primaryimage"},"thumbnailUrl":"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/12\/airbnb-2022-winter-release-1.png","datePublished":"2022-12-28T10:22:43+00:00","dateModified":"2025-08-19T09:31:44+00:00","description":"Con la versi\u00f3n de invierno de Airbnb 2022, \u00bfqu\u00e9 nuevas funciones se incorporan y c\u00f3mo afectar\u00e1n a los anfitriones? Compartamos algunas opiniones sobre estas actualizaciones.","breadcrumb":{"@id":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#primaryimage","url":"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/12\/airbnb-2022-winter-release-1.png","contentUrl":"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/12\/airbnb-2022-winter-release-1.png","width":1920,"height":1080,"caption":"Three iPhones displaying the Airbnb host onboarding flow: Superhost matching, first guest selection, and support access."},{"@type":"BreadcrumbList","@id":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hostex.io\/blog\/"},{"@type":"ListItem","position":2,"name":"What You Should Know About The Airbnb 2022 Winter Release?"}]},{"@type":"WebSite","@id":"https:\/\/hostex.io\/blog\/#website","url":"https:\/\/hostex.io\/blog\/","name":"Hostex","description":"Ponga su alquiler vacacional en piloto autom\u00e1tico con IA","publisher":{"@id":"https:\/\/hostex.io\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hostex.io\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hostex.io\/blog\/#organization","name":"Hostex","url":"https:\/\/hostex.io\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hostex.io\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/11\/cropped-cropped-cropped-cropped-cropped-Hostex_logo-3-1.png","contentUrl":"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/11\/cropped-cropped-cropped-cropped-cropped-Hostex_logo-3-1.png","width":1979,"height":506,"caption":"Hostex"},"image":{"@id":"https:\/\/hostex.io\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Hostex.io\/","https:\/\/x.com\/HostexApp","https:\/\/www.instagram.com\/hostex.io\/","https:\/\/www.youtube.com\/channel\/UCGeqVXi3XuEkCwFyoH6WxPA"]},{"@type":"Person","@id":"https:\/\/hostex.io\/blog\/#\/schema\/person\/21abfcce32dee155095d3e903b35d680","name":"Daniel Altman","sameAs":["https:\/\/hostex.io\/","https:\/\/www.facebook.com\/Hostex.io","https:\/\/www.instagram.com\/hostex.io\/","https:\/\/x.com\/https:\/\/twitter.com\/HostexApp","https:\/\/www.youtube.com\/channel\/UCGeqVXi3XuEkCwFyoH6WxPA"],"url":"https:\/\/hostex.io\/blog\/es\/author\/root\/"}]}},"_links":{"self":[{"href":"https:\/\/hostex.io\/blog\/es\/wp-json\/wp\/v2\/posts\/359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hostex.io\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hostex.io\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hostex.io\/blog\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hostex.io\/blog\/es\/wp-json\/wp\/v2\/comments?post=359"}],"version-history":[{"count":17,"href":"https:\/\/hostex.io\/blog\/es\/wp-json\/wp\/v2\/posts\/359\/revisions"}],"predecessor-version":[{"id":1430,"href":"https:\/\/hostex.io\/blog\/es\/wp-json\/wp\/v2\/posts\/359\/revisions\/1430"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hostex.io\/blog\/es\/wp-json\/wp\/v2\/media\/1429"}],"wp:attachment":[{"href":"https:\/\/hostex.io\/blog\/es\/wp-json\/wp\/v2\/media?parent=359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hostex.io\/blog\/es\/wp-json\/wp\/v2\/categories?post=359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hostex.io\/blog\/es\/wp-json\/wp\/v2\/tags?post=359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}