{"id":359,"date":"2022-12-28T10:22:43","date_gmt":"2022-12-28T10:22:43","guid":{"rendered":"https:\/\/hostex.io\/blog\/?p=359"},"modified":"2025-08-19T09:31:44","modified_gmt":"2025-08-19T09:31:44","slug":"the-airbnb-2022-winter-release","status":"publish","type":"post","link":"https:\/\/hostex.io\/blog\/fr\/the-airbnb-2022-winter-release\/","title":{"rendered":"Que devez-vous savoir sur la sortie d&#039;hiver d&#039;Airbnb 2022 ?"},"content":{"rendered":"<p>Chaque nouvelle mise \u00e0 jour d&#039;Airbnb s&#039;accompagne d&#039;un certain nombre de nouvelles fonctionnalit\u00e9s int\u00e9ressantes, telles que AirCover et Split Stays dans Airbnb <a rel=\"noreferrer noopener\" href=\"https:\/\/news.airbnb.com\/product-releases\/airbnb-2022-summer-release\/\" target=\"_blank\">Sortie \u00e9t\u00e9 2022<\/a>, qui a \u00e9t\u00e9 bien accueilli par la plupart des h\u00f4tes.<\/p>\n\n\n\n<p>Cependant, ces mises \u00e0 jour peuvent parfois \u00eatre quelque peu controvers\u00e9es et pourraient transformer ce qui \u00e9tait un avantage pour certains h\u00f4tes en un inconv\u00e9nient.<\/p>\n\n\n\n<p>Avec <a rel=\"noreferrer noopener\" href=\"https:\/\/www.airbnb.com\/2022-winter\" target=\"_blank\">la sortie d&#039;hiver d&#039;Airbnb 2022<\/a>, quelles sont les nouvelles fonctionnalit\u00e9s \u00e0 venir et comment affecteront-elles les h\u00f4tes ? Partageons quelques points de vue sur ces mises \u00e0 jour.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>1. Encore plus de couverture a\u00e9rienne<\/strong><\/h2>\n\n\n\n<p><a rel=\"noreferrer noopener\" href=\"https:\/\/www.airbnb.com\/aircover-for-hosts\" target=\"_blank\">AirCover pour les h\u00f4tes<\/a> est une protection compl\u00e8te pour les h\u00f4tes. Elle comprend la v\u00e9rification de l&#039;identit\u00e9 des voyageurs, le contr\u00f4le des r\u00e9servations, la protection contre les dommages caus\u00e9s \u00e0 l&#039;h\u00f4te, l&#039;assurance responsabilit\u00e9 civile de l&#039;h\u00f4te, l&#039;assurance responsabilit\u00e9 civile de l&#039;exp\u00e9rience et une ligne de s\u00e9curit\u00e9 24 heures sur 24. Ces protections sont encore am\u00e9lior\u00e9es dans la version d&#039;hiver 2022 d&#039;Airbnb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Protection contre les dommages $3M<\/strong><\/h3>\n\n\n\n<p>Vrbo et Booking.com proposent une assurance responsabilit\u00e9 civile $1 000 000 aux h\u00f4tes, et si Airbnb veut se concentrer encore plus, il devra placer la barre encore plus haut, c&#039;est pourquoi AirCover propose d\u00e9sormais une protection pour les voitures et les bateaux gar\u00e9s dans la propri\u00e9t\u00e9 r\u00e9pertori\u00e9e, ainsi qu&#039;une protection suppl\u00e9mentaire pour les \u0153uvres d&#039;art et les objets de valeur et une protection accrue contre les dommages <strong>de 1 TP4T1 million \u00e0 1 TP4T3 millions<\/strong>.<\/p>\n\n\n\n<p>Cette protection est certainement attrayante pour les nouveaux h\u00f4tes. Lorsque vous d\u00e9butez en tant qu&#039;h\u00f4te \u00e0 court terme, vous \u00eates tenu d&#039;offrir une s\u00e9rie d&#039;actifs de grande valeur dans votre propri\u00e9t\u00e9 locative qui attireront des r\u00e9servations, et lorsque vous autorisez des \u00e9trangers \u00e0 s\u00e9journer dans votre maison, vous aurez l&#039;esprit tranquille si vous sentez que vos actifs sont sous protection.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>V\u00e9rification de l&#039;identit\u00e9 des invit\u00e9s<\/strong><\/h3>\n\n\n\n<p>Le syst\u00e8me de v\u00e9rification complet v\u00e9rifie des d\u00e9tails tels que le nom, l&#039;adresse, la pi\u00e8ce d&#039;identit\u00e9 gouvernementale, etc. pour confirmer l&#039;identit\u00e9 des voyageurs qui r\u00e9servent sur Airbnb.<\/p>\n\n\n\n<p>Actuellement, cela couvre 90% de toutes les r\u00e9servations, ce qui constitue un \u00e9norme avantage pour les h\u00f4tes car ils peuvent compter sur une id\u00e9e plus claire des personnes qui s\u00e9journeront dans leur propri\u00e9t\u00e9, gr\u00e2ce \u00e0 un processus de v\u00e9rification plus strict. D&#039;ici le printemps 2023, 100% de toutes les r\u00e9servations mondiales seront v\u00e9rifi\u00e9es.<\/p>\n\n\n\n<p>Cette fonctionnalit\u00e9 est importante pour les h\u00f4tes, <strong>surtout les nouveaux<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Fonctionnalit\u00e9s de filtrage des r\u00e9servations<\/strong><\/h3>\n\n\n\n<p>La technologie exclusive d&#039;Airbnb analyse des centaines de facteurs dans chaque r\u00e9servation et <strong>bloque certaines r\u00e9servations qui pr\u00e9sentent un risque \u00e9lev\u00e9 de perturbations et de dommages mat\u00e9riels<\/strong>.<\/p>\n\n\n\n<p>Airbnb affirme d\u00e9sormais que cela est exclusif \u00e0 ses plateformes, mais on ne sait pas clairement quels facteurs sp\u00e9cifiques la technologie prend en compte et comment elle peut faire la diff\u00e9rence entre les clients potentiellement probl\u00e9matiques et les grands groupes bien \u00e9lev\u00e9s. <\/p>\n\n\n\n<p>Cependant, cette fonctionnalit\u00e9 bloquera toute demande qui pourrait sembler constituer une violation potentielle des r\u00e8gles et sera s\u00fbrement bien accueillie par la majorit\u00e9 des h\u00f4tes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Il est plus facile de d\u00e9poser une r\u00e9clamation<\/strong><\/h3>\n\n\n\n<p>Cette fonctionnalit\u00e9 est con\u00e7ue pour permettre aux h\u00f4tes d&#039;informer plus facilement Airbnb et les voyageurs des objets endommag\u00e9s, perdus ou vol\u00e9s. En suivant un processus simple et intuitif, les h\u00f4tes peuvent informer Airbnb d&#039;un objet cass\u00e9 ou manquant, de sa valeur, de son \u00e2ge et de la date \u00e0 laquelle il s&#039;est produit. Un r\u00e9sum\u00e9 de la r\u00e9clamation est ensuite transmis \u00e0 la plateforme et au voyageur. L&#039;objectif est d&#039;offrir une protection suppl\u00e9mentaire aux h\u00f4tes tout en les rassurant sur le remboursement dans le pire des cas.<\/p>\n\n\n\n<p>Mais pour les h\u00f4tes, le probl\u00e8me n\u2019est peut-\u00eatre pas le processus de r\u00e9clamation pr\u00e9c\u00e9dent, mais le fait qu\u2019Airbnb ait tendance \u00e0 privil\u00e9gier la protection des droits des voyageurs lors de la prise de d\u00e9cisions. Peut-\u00eatre que davantage d\u2019h\u00f4tes accueilleraient favorablement cette nuisance.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/news.airbnb.com\/wp-content\/uploads\/sites\/4\/2022\/05\/AirCover_PS_ENG_02.jpg?w=1024&amp;resize=3000%2C2000\" alt=\" \"\/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>2. La toute nouvelle configuration d&#039;Airbnb<\/strong><\/h2>\n\n\n\n<p>La r\u00e9cession \u00e0 venir pourrait inciter davantage de personnes \u00e0 essayer de gagner plus en louant leurs logements sur Airbnb. Au cours de l&#039;ann\u00e9e \u00e9coul\u00e9e, pr\u00e8s de 30 millions de personnes ont visit\u00e9 Airbnb pour en savoir plus sur l&#039;h\u00e9bergement. Ainsi, \u00e0 chaque nouvelle mise \u00e0 jour de produit depuis 2021, Airbnb s&#039;efforce de r\u00e9duire les obstacles pour que les nouveaux h\u00f4tes puissent se lancer.<\/p>\n\n\n\n<p>Dans cet esprit, Airbnb souhaite qu&#039;il soit beaucoup plus facile d&#039;ajouter votre propri\u00e9t\u00e9 en tant qu&#039;h\u00e9bergement r\u00e9servable. La version d&#039;hiver 2022 d&#039;Airbnb Set Up est con\u00e7ue pour rendre cela possible.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Accompagnement personnalis\u00e9 par un Superhost<\/strong><\/h3>\n\n\n\n<p>Ce nouveau flux d&#039;int\u00e9gration offre aux nouveaux h\u00f4tes la possibilit\u00e9 d&#039;\u00eatre mis en relation avec un Superhost existant dans la m\u00eame r\u00e9gion qui peut les guider et les conseiller gratuitement tout au long du processus d&#039;installation. <\/p>\n\n\n\n<p>Les nouveaux h\u00f4tes peuvent passer des appels vid\u00e9o et partager leur \u00e9cran avec leur Superh\u00f4te partenaire, qui les aidera \u00e0 s\u00e9lectionner des photos, \u00e0 r\u00e9diger votre annonce et \u00e0 partager tous les conseils qu&#039;ils pourraient avoir.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Un client exp\u00e9riment\u00e9 pour la premi\u00e8re r\u00e9servation<\/strong><\/h3>\n\n\n\n<p>D\u00e9sormais, les nouveaux h\u00f4tes peuvent choisir d&#039;h\u00e9berger un voyageur exp\u00e9riment\u00e9 pour leur premi\u00e8re r\u00e9servation, c&#039;est-\u00e0-dire une personne ayant au moins trois s\u00e9jours et un bon historique sur Airbnb.<\/p>\n\n\n\n<p>Cela rend la proposition moins intimidante pour les nouveaux h\u00f4tes, qui peuvent utiliser l&#039;exp\u00e9rience pour s&#039;am\u00e9liorer et agir sur les commentaires des clients.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Assistance sp\u00e9cialis\u00e9e d&#039;Airbnb<\/strong><\/h3>\n\n\n\n<p>Les nouveaux h\u00f4tes peuvent contacter les agents d&#039;assistance d&#039;Airbnb pour obtenir de l&#039;aide sur n&#039;importe quel sujet dans 42 langues, tout comme pour les superh\u00f4tes.<\/p>\n\n\n\n<p>Il est extr\u00eamement convivial pour la plupart des nouveaux h\u00f4tes et il semble qu&#039;Airbnb soit pr\u00eat \u00e0 consacrer plus de temps et d&#039;argent pour mettre les nouveaux h\u00f4tes sur la voie du succ\u00e8s.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"746\" src=\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/image-7-1024x746.png\" alt=\"\" class=\"wp-image-1428\" srcset=\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/image-7-1024x746.png 1024w, https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/image-7-300x219.png 300w, https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/image-7-768x560.png 768w, https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/image-7.png 1212w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>3. Nouvelles cat\u00e9gories Airbnb<\/strong><\/h2>\n\n\n\n<p>En mai, Airbnb a lanc\u00e9 une nouvelle m\u00e9thode de recherche con\u00e7ue autour des cat\u00e9gories Airbnb. Le fait de disposer de cat\u00e9gories distinctes permettra au propri\u00e9taire de commercialiser sa maison de vacances de mani\u00e8re \u00e0 mieux r\u00e9pondre aux besoins et aux d\u00e9sirs des clients potentiels.<\/p>\n\n\n\n<p>D\u00e9sormais, la version hivernale d&#039;Airbnb comprend six nouvelles cat\u00e9gories pour aider les h\u00f4tes \u00e0 identifier leur march\u00e9 et leur client\u00e8le. Les h\u00f4tes pourront \u00e9galement voir dans quelle cat\u00e9gorie se trouve leur logement et ajouter des d\u00e9tails sp\u00e9cifiques \u00e0 la cat\u00e9gorie \u00e0 leur annonce.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/a0.muscache.com\/im\/pictures\/8ecbc24f-607a-4fa2-be23-61b7c1028b37.jpg?im_w=2560\" alt=\"A laptop and a phone show the Airbnb homepage with two rows of homes from a new Airbnb Winter Release category called Hanoks, which features traditional 14th century South Korean homes made of natural materials.\"\/><\/figure>\n\n\n\n<p>Airbnb am\u00e9liore \u00e9galement les cat\u00e9gories affich\u00e9es. Par exemple, lorsque vous lancez l&#039;application, vous verrez la cat\u00e9gorie Vignobles si vous avez r\u00e9cemment recherch\u00e9 des logements \u00e0 Napa. <\/p>\n\n\n\n<p>De plus, vous verrez plus de d\u00e9tails lorsque vous consulterez les cat\u00e9gories dans les r\u00e9sultats de recherche. Par exemple, les maisons avec une vue imprenable indiqueront le type de vue, et les maisons proches des parcs nationaux indiqueront la distance jusqu&#039;\u00e0 l&#039;entr\u00e9e du parc.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>4. R\u00e8gles de base pour les invit\u00e9s<\/strong><\/h2>\n\n\n\n<p>Les r\u00e8gles de base sont des r\u00e8gles qui ne peuvent pas \u00eatre enfreintes par les voyageurs. C&#039;est un ajout bienvenu pour les h\u00f4tes qui souhaitent appliquer des politiques sp\u00e9cifiques, car les voyageurs doivent lire et accepter toutes les r\u00e8gles de base avant de r\u00e9server. Un voyageur sera soit averti, suspendu ou expuls\u00e9 d&#039;Airbnb si ces r\u00e8gles ne sont pas respect\u00e9es.<\/p>\n\n\n\n<p>Le fait est que chaque h\u00f4te a toujours \u00e9tabli des r\u00e8gles de s\u00e9jour, mais il s&#039;agit simplement d&#039;un SMS de notification envoy\u00e9 aux voyageurs, et son efficacit\u00e9 ou non d\u00e9pend de la force de l&#039;application. J&#039;esp\u00e8re que cette nouvelle fonctionnalit\u00e9 d&#039;Airbnb pourra vraiment jouer un r\u00f4le dans la limitation du comportement des voyageurs.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>5. Mise \u00e0 jour des avis<\/strong><\/h2>\n\n\n\n<p>Les voyageurs et les h\u00f4tes peuvent d\u00e9sormais ajouter des balises \u00e0 leurs commentaires pour fournir des d\u00e9tails plus pr\u00e9cis sur le s\u00e9jour.<\/p>\n\n\n\n<p>Pour les h\u00f4tes, cette fonctionnalit\u00e9 leur permettra d&#039;enregistrer notamment si le voyageur a enfreint des r\u00e8gles de base ou s&#039;il a d\u00e9pass\u00e9 son heure de d\u00e9part. De cette fa\u00e7on, lorsque d&#039;autres h\u00f4tes recevront une demande de r\u00e9servation, ils verront ces d\u00e9tails et prendront une meilleure d\u00e9cision.<\/p>\n\n\n\n<p>Airbnb a \u00e9galement \u00e9largi les raisons pour lesquelles un commentaire peut \u00eatre contest\u00e9 et permet d\u00e9sormais aux h\u00f4tes de demander plus facilement la suppression de commentaires injustes et de repr\u00e9sailles, quelle que soit la date \u00e0 laquelle ils ont \u00e9t\u00e9 laiss\u00e9s.<\/p>\n\n\n\n<p>Vous pouvez envoyer des avis aux clients, consulter et r\u00e9pondre aux avis des clients via <a rel=\"noreferrer noopener\" href=\"https:\/\/hostex.io\/\" target=\"_blank\">Hostex<\/a>, et <a rel=\"noreferrer noopener\" href=\"https:\/\/hostex.io\/blog\/airbnb-host-reviews-and-how-to-automate-them-with-review-examples\/\" target=\"_blank\">toutes ces actions peuvent \u00eatre automatis\u00e9es<\/a>. <strong>Inscrivez-vous maintenant sur Hostex pour automatiser vos multiples canaux d&#039;annonces et d&#039;avis !<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/hostex.io\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"413\" src=\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/16_9\u5934\u56fe-1-1024x413.png\" alt=\"\" class=\"wp-image-1400\" srcset=\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/16_9\u5934\u56fe-1-1024x413.png 1024w, https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/16_9\u5934\u56fe-1-300x121.png 300w, https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/16_9\u5934\u56fe-1-768x310.png 768w, https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/16_9\u5934\u56fe-1-1536x620.png 1536w, https:\/\/hostex.io\/blog\/wp-content\/uploads\/2024\/02\/16_9\u5934\u56fe-1-2048x827.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>6. <strong>Paiement rapide<\/strong><\/strong><\/h2>\n\n\n\n<p>Le nouveau&nbsp;<strong>Paiement rapide<\/strong>&nbsp;la fonctionnalit\u00e9 permet aux h\u00f4tes de choisir de recevoir les paiements sur leur carte de d\u00e9bit en 30 minutes ou moins (disponible aux \u00c9tats-Unis uniquement).<\/p>\n\n\n\n<p>Cela contribuera grandement \u00e0 soulager la pression sur les petits h\u00e9bergeurs qui sont tr\u00e8s sensibles aux flux de tr\u00e9sorerie. Il n&#039;est pas n\u00e9cessaire d&#039;attendre 24 heures pour \u00eatre pay\u00e9 et les h\u00f4tes se sentiront plus \u00e0 l&#039;aise avec leur situation financi\u00e8re.<\/p>\n\n\n\n<p>Et Airbnb facturera des frais de 1,5% (avec des frais maximum de $15 USD, taxes comprises si applicables), ce qui peut \u00e9galement \u00eatre un moyen pour eux d&#039;augmenter leurs b\u00e9n\u00e9fices.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>7. Tarifs avec forfait m\u00e9nage<\/strong><\/h2>\n\n\n\n<p>Airbnb inclura les frais de m\u00e9nage dans le prix de r\u00e9servation affich\u00e9, ce qui permettra au client de voir le co\u00fbt total qu&#039;il paiera \u00e0 l&#039;avance lors de la navigation dans l&#039;annonce, au lieu d&#039;attendre que la r\u00e9servation soit confirm\u00e9e, ce qui facilitera la prise de d\u00e9cision et \u00e9vitera une perte de temps inutile.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p><strong>Clause de non-responsabilit\u00e9: <a href=\"https:\/\/hostex.io\/\" target=\"_blank\" rel=\"noreferrer noopener\">Hostex<\/a> est un partenaire logiciel d&#039;Airbnb. Ce message, y compris toutes les d\u00e9clarations ou affirmations qu&#039;il contient, provient uniquement d&#039;Hostex et n&#039;est en aucun cas approuv\u00e9, directement affili\u00e9, autoris\u00e9 ou sponsoris\u00e9 par Airbnb.<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Avec la sortie d&#039;hiver d&#039;Airbnb 2022, quelles sont les nouvelles fonctionnalit\u00e9s \u00e0 venir et quel impact auront-elles sur les h\u00f4tes ? Partageons quelques points de vue sur ces mises \u00e0 jour.<\/p>","protected":false},"author":1,"featured_media":1429,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[78],"tags":[88],"class_list":["post-359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-insights","tag-airbnb-release"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>What You Should Know About The Airbnb 2022 Winter Release? - Hostex<\/title>\n<meta name=\"description\" content=\"With the Airbnb 2022 Winter Release, what new features are coming, and how will they affect hosts? Let\u2019s share some views on these updates.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hostex.io\/blog\/fr\/the-airbnb-2022-winter-release\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"What You Should Know About The Airbnb 2022 Winter Release? - Hostex\" \/>\n<meta property=\"og:description\" content=\"With the Airbnb 2022 Winter Release, what new features are coming, and how will they affect hosts? Let\u2019s share some views on these updates.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hostex.io\/blog\/fr\/the-airbnb-2022-winter-release\/\" \/>\n<meta property=\"og:site_name\" content=\"Hostex\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Hostex.io\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Hostex.io\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-28T10:22:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-19T09:31:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/12\/airbnb-2022-winter-release-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Daniel Altman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/HostexApp\" \/>\n<meta name=\"twitter:site\" content=\"@HostexApp\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Altman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/\"},\"author\":{\"name\":\"Daniel Altman\",\"@id\":\"https:\/\/hostex.io\/blog\/#\/schema\/person\/21abfcce32dee155095d3e903b35d680\"},\"headline\":\"What You Should Know About The Airbnb 2022 Winter Release?\",\"datePublished\":\"2022-12-28T10:22:43+00:00\",\"dateModified\":\"2025-08-19T09:31:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/\"},\"wordCount\":1392,\"commentCount\":19,\"publisher\":{\"@id\":\"https:\/\/hostex.io\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/12\/airbnb-2022-winter-release-1.png\",\"keywords\":[\"airbnb release\"],\"articleSection\":[\"Insights\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/\",\"url\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/\",\"name\":\"What You Should Know About The Airbnb 2022 Winter Release? - Hostex\",\"isPartOf\":{\"@id\":\"https:\/\/hostex.io\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/12\/airbnb-2022-winter-release-1.png\",\"datePublished\":\"2022-12-28T10:22:43+00:00\",\"dateModified\":\"2025-08-19T09:31:44+00:00\",\"description\":\"With the Airbnb 2022 Winter Release, what new features are coming, and how will they affect hosts? Let\u2019s share some views on these updates.\",\"breadcrumb\":{\"@id\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#primaryimage\",\"url\":\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/12\/airbnb-2022-winter-release-1.png\",\"contentUrl\":\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/12\/airbnb-2022-winter-release-1.png\",\"width\":1920,\"height\":1080,\"caption\":\"Three iPhones displaying the Airbnb host onboarding flow: Superhost matching, first guest selection, and support access.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hostex.io\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"What You Should Know About The Airbnb 2022 Winter Release?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hostex.io\/blog\/#website\",\"url\":\"https:\/\/hostex.io\/blog\/\",\"name\":\"Hostex\",\"description\":\"Put your vacation rental on autopilot with AI\",\"publisher\":{\"@id\":\"https:\/\/hostex.io\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hostex.io\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hostex.io\/blog\/#organization\",\"name\":\"Hostex\",\"url\":\"https:\/\/hostex.io\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/hostex.io\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/11\/cropped-cropped-cropped-cropped-cropped-Hostex_logo-3-1.png\",\"contentUrl\":\"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/11\/cropped-cropped-cropped-cropped-cropped-Hostex_logo-3-1.png\",\"width\":1979,\"height\":506,\"caption\":\"Hostex\"},\"image\":{\"@id\":\"https:\/\/hostex.io\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Hostex.io\/\",\"https:\/\/x.com\/HostexApp\",\"https:\/\/www.instagram.com\/hostex.io\/\",\"https:\/\/www.youtube.com\/channel\/UCGeqVXi3XuEkCwFyoH6WxPA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/hostex.io\/blog\/#\/schema\/person\/21abfcce32dee155095d3e903b35d680\",\"name\":\"Daniel Altman\",\"sameAs\":[\"https:\/\/hostex.io\/\",\"https:\/\/www.facebook.com\/Hostex.io\",\"https:\/\/www.instagram.com\/hostex.io\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/HostexApp\",\"https:\/\/www.youtube.com\/channel\/UCGeqVXi3XuEkCwFyoH6WxPA\"],\"url\":\"https:\/\/hostex.io\/blog\/fr\/author\/root\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"What You Should Know About The Airbnb 2022 Winter Release? - Hostex","description":"Avec la sortie d&#039;hiver d&#039;Airbnb 2022, quelles sont les nouvelles fonctionnalit\u00e9s \u00e0 venir et quel impact auront-elles sur les h\u00f4tes ? Partageons quelques points de vue sur ces mises \u00e0 jour.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hostex.io\/blog\/fr\/the-airbnb-2022-winter-release\/","og_locale":"fr_FR","og_type":"article","og_title":"What You Should Know About The Airbnb 2022 Winter Release? - Hostex","og_description":"With the Airbnb 2022 Winter Release, what new features are coming, and how will they affect hosts? Let\u2019s share some views on these updates.","og_url":"https:\/\/hostex.io\/blog\/fr\/the-airbnb-2022-winter-release\/","og_site_name":"Hostex","article_publisher":"https:\/\/www.facebook.com\/Hostex.io\/","article_author":"https:\/\/www.facebook.com\/Hostex.io","article_published_time":"2022-12-28T10:22:43+00:00","article_modified_time":"2025-08-19T09:31:44+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/12\/airbnb-2022-winter-release-1.png","type":"image\/png"}],"author":"Daniel Altman","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/HostexApp","twitter_site":"@HostexApp","twitter_misc":{"\u00c9crit par":"Daniel Altman","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#article","isPartOf":{"@id":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/"},"author":{"name":"Daniel Altman","@id":"https:\/\/hostex.io\/blog\/#\/schema\/person\/21abfcce32dee155095d3e903b35d680"},"headline":"What You Should Know About The Airbnb 2022 Winter Release?","datePublished":"2022-12-28T10:22:43+00:00","dateModified":"2025-08-19T09:31:44+00:00","mainEntityOfPage":{"@id":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/"},"wordCount":1392,"commentCount":19,"publisher":{"@id":"https:\/\/hostex.io\/blog\/#organization"},"image":{"@id":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#primaryimage"},"thumbnailUrl":"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/12\/airbnb-2022-winter-release-1.png","keywords":["airbnb release"],"articleSection":["Insights"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/","url":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/","name":"What You Should Know About The Airbnb 2022 Winter Release? - Hostex","isPartOf":{"@id":"https:\/\/hostex.io\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#primaryimage"},"image":{"@id":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#primaryimage"},"thumbnailUrl":"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/12\/airbnb-2022-winter-release-1.png","datePublished":"2022-12-28T10:22:43+00:00","dateModified":"2025-08-19T09:31:44+00:00","description":"Avec la sortie d&#039;hiver d&#039;Airbnb 2022, quelles sont les nouvelles fonctionnalit\u00e9s \u00e0 venir et quel impact auront-elles sur les h\u00f4tes ? Partageons quelques points de vue sur ces mises \u00e0 jour.","breadcrumb":{"@id":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#primaryimage","url":"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/12\/airbnb-2022-winter-release-1.png","contentUrl":"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/12\/airbnb-2022-winter-release-1.png","width":1920,"height":1080,"caption":"Three iPhones displaying the Airbnb host onboarding flow: Superhost matching, first guest selection, and support access."},{"@type":"BreadcrumbList","@id":"https:\/\/hostex.io\/blog\/the-airbnb-2022-winter-release\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hostex.io\/blog\/"},{"@type":"ListItem","position":2,"name":"What You Should Know About The Airbnb 2022 Winter Release?"}]},{"@type":"WebSite","@id":"https:\/\/hostex.io\/blog\/#website","url":"https:\/\/hostex.io\/blog\/","name":"Hostex","description":"Mettez votre location de vacances en pilotage automatique avec l&#039;IA","publisher":{"@id":"https:\/\/hostex.io\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hostex.io\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/hostex.io\/blog\/#organization","name":"Hostex","url":"https:\/\/hostex.io\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hostex.io\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/11\/cropped-cropped-cropped-cropped-cropped-Hostex_logo-3-1.png","contentUrl":"https:\/\/hostex.io\/blog\/wp-content\/uploads\/2022\/11\/cropped-cropped-cropped-cropped-cropped-Hostex_logo-3-1.png","width":1979,"height":506,"caption":"Hostex"},"image":{"@id":"https:\/\/hostex.io\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Hostex.io\/","https:\/\/x.com\/HostexApp","https:\/\/www.instagram.com\/hostex.io\/","https:\/\/www.youtube.com\/channel\/UCGeqVXi3XuEkCwFyoH6WxPA"]},{"@type":"Person","@id":"https:\/\/hostex.io\/blog\/#\/schema\/person\/21abfcce32dee155095d3e903b35d680","name":"Daniel Altman","sameAs":["https:\/\/hostex.io\/","https:\/\/www.facebook.com\/Hostex.io","https:\/\/www.instagram.com\/hostex.io\/","https:\/\/x.com\/https:\/\/twitter.com\/HostexApp","https:\/\/www.youtube.com\/channel\/UCGeqVXi3XuEkCwFyoH6WxPA"],"url":"https:\/\/hostex.io\/blog\/fr\/author\/root\/"}]}},"_links":{"self":[{"href":"https:\/\/hostex.io\/blog\/fr\/wp-json\/wp\/v2\/posts\/359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hostex.io\/blog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hostex.io\/blog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hostex.io\/blog\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hostex.io\/blog\/fr\/wp-json\/wp\/v2\/comments?post=359"}],"version-history":[{"count":17,"href":"https:\/\/hostex.io\/blog\/fr\/wp-json\/wp\/v2\/posts\/359\/revisions"}],"predecessor-version":[{"id":1430,"href":"https:\/\/hostex.io\/blog\/fr\/wp-json\/wp\/v2\/posts\/359\/revisions\/1430"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hostex.io\/blog\/fr\/wp-json\/wp\/v2\/media\/1429"}],"wp:attachment":[{"href":"https:\/\/hostex.io\/blog\/fr\/wp-json\/wp\/v2\/media?parent=359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hostex.io\/blog\/fr\/wp-json\/wp\/v2\/categories?post=359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hostex.io\/blog\/fr\/wp-json\/wp\/v2\/tags?post=359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}